﻿{"id":158,"date":"2017-02-14T14:12:16","date_gmt":"2017-02-14T13:12:16","guid":{"rendered":"https:\/\/forms.fh-joanneum.at\/int\/?page_id=158"},"modified":"2020-02-18T16:01:26","modified_gmt":"2020-02-18T15:01:26","slug":"isc","status":"publish","type":"page","link":"https:\/\/forms.fh-joanneum.at\/int\/isc\/","title":{"rendered":"Antrag auf Ausstellung des ISC (Intercultural Skills Certificate)"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-74\" src=\"https:\/\/forms.fh-joanneum.at\/int\/wp-content\/uploads\/sites\/2\/2016\/03\/en.png\" alt=\"en\" width=\"22\" height=\"16\" \/>\u00a0<a href=\"http:\/\/fhj.to\/isc-en\">ENGLISH VERSION<\/a>\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-74\" src=\"https:\/\/forms.fh-joanneum.at\/int\/wp-content\/uploads\/sites\/2\/2016\/03\/en.png\" alt=\"en\" width=\"22\" height=\"16\" \/><\/p>\n<p>Damit Sie ihr Intercultural Skills Certificate (ISC) bald in H\u00e4nden halten k\u00f6nnen, f\u00fcllen Sie bitte das Formular vollst\u00e4ndig aus.<\/p>\n<p>Die Ausstellung des ISC dauert ca. zwei Wochen.<\/p>\n<p>Wir verst\u00e4ndigen Sie per E-Mail, wenn Sie das ISC im International Office abholen k\u00f6nnen.<\/p>\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_8' style='display:none'><form method='post' enctype='multipart\/form-data'  id='gform_8'  action='\/int\/wp-json\/wp\/v2\/pages\/158' data-formid='8' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_8' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_8_1\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Pers\u00f6nliche Daten<\/h2><\/li><li id=\"field_8_2\" class=\"gfield gfield--type-radio gfield--type-choice gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' >Anrede<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_radio'><ul class='gfield_radio' id='input_8_2'>\n\t\t\t<li class='gchoice gchoice_8_2_0'>\n\t\t\t\t<input name='input_2' type='radio' value='Frau'  id='choice_8_2_0'    \/>\n\t\t\t\t<label for='choice_8_2_0' id='label_8_2_0' class='gform-field-label gform-field-label--type-inline'>Frau<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_2_1'>\n\t\t\t\t<input name='input_2' type='radio' value='Herr'  id='choice_8_2_1'    \/>\n\t\t\t\t<label for='choice_8_2_1' id='label_8_2_1' class='gform-field-label gform-field-label--type-inline'>Herr<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_2_2'>\n\t\t\t\t<input name='input_2' type='radio' value='Divers'  id='choice_8_2_2'    \/>\n\t\t\t\t<label for='choice_8_2_2' id='label_8_2_2' class='gform-field-label gform-field-label--type-inline'>Divers<\/label>\n\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_8_3\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_3'>Vorname<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_8_3' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_4\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_4'>Nachname<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_8_4' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_5\" class=\"gfield gfield--type-email gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_5'>E-Mail Adresse<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_5' id='input_8_5' type='email' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_8_6\" class=\"gfield gfield--type-date gfield--input-type-datedropdown gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' >Geburtsdatum<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div id='input_8_6' class='ginput_container ginput_complex gform-grid-row'><div class=\"clear-multi\"><div class='gfield_date_dropdown_day ginput_container ginput_container_date gform-grid-col' id='input_8_6_2_container'><label for='input_8_6_2' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Tag<\/label><select name='input_6[]' id='input_8_6_2'   aria-required='true'  ><option value=''>Tag<\/option><option value='1' >1<\/option><option value='2' >2<\/option><option value='3' >3<\/option><option value='4' >4<\/option><option value='5' >5<\/option><option value='6' >6<\/option><option value='7' >7<\/option><option value='8' >8<\/option><option value='9' >9<\/option><option value='10' >10<\/option><option value='11' >11<\/option><option value='12' >12<\/option><option value='13' >13<\/option><option value='14' >14<\/option><option value='15' >15<\/option><option value='16' >16<\/option><option value='17' >17<\/option><option value='18' >18<\/option><option value='19' >19<\/option><option value='20' >20<\/option><option value='21' >21<\/option><option value='22' >22<\/option><option value='23' >23<\/option><option value='24' >24<\/option><option value='25' >25<\/option><option value='26' >26<\/option><option value='27' >27<\/option><option value='28' >28<\/option><option value='29' >29<\/option><option value='30' >30<\/option><option value='31' >31<\/option><\/select><\/div><div class='gfield_date_dropdown_month ginput_container ginput_container_date gform-grid-col' id='input_8_6_1_container'><label for='input_8_6_1' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Monat<\/label><select name='input_6[]' id='input_8_6_1'   aria-required='true'  ><option value=''>Monat<\/option><option value='1' >1<\/option><option value='2' >2<\/option><option value='3' >3<\/option><option value='4' >4<\/option><option value='5' >5<\/option><option value='6' >6<\/option><option value='7' >7<\/option><option value='8' >8<\/option><option value='9' >9<\/option><option value='10' >10<\/option><option value='11' >11<\/option><option value='12' >12<\/option><\/select><\/div><div class='gfield_date_dropdown_year ginput_container ginput_container_date gform-grid-col' id='input_8_6_3_container'><label for='input_8_6_3' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Jahr<\/label><select name='input_6[]' id='input_8_6_3'   aria-required='true'  ><option value=''>Jahr<\/option><option value='2027' >2027<\/option><option value='2026' >2026<\/option><option value='2025' >2025<\/option><option value='2024' >2024<\/option><option value='2023' >2023<\/option><option value='2022' >2022<\/option><option value='2021' >2021<\/option><option value='2020' >2020<\/option><option value='2019' >2019<\/option><option value='2018' >2018<\/option><option value='2017' >2017<\/option><option value='2016' >2016<\/option><option value='2015' >2015<\/option><option value='2014' >2014<\/option><option value='2013' >2013<\/option><option value='2012' >2012<\/option><option value='2011' >2011<\/option><option value='2010' >2010<\/option><option value='2009' >2009<\/option><option value='2008' >2008<\/option><option value='2007' >2007<\/option><option value='2006' >2006<\/option><option value='2005' >2005<\/option><option value='2004' >2004<\/option><option value='2003' >2003<\/option><option value='2002' >2002<\/option><option value='2001' >2001<\/option><option value='2000' >2000<\/option><option value='1999' >1999<\/option><option value='1998' >1998<\/option><option value='1997' >1997<\/option><option value='1996' >1996<\/option><option value='1995' >1995<\/option><option value='1994' >1994<\/option><option value='1993' >1993<\/option><option value='1992' >1992<\/option><option value='1991' >1991<\/option><option value='1990' >1990<\/option><option value='1989' >1989<\/option><option value='1988' >1988<\/option><option value='1987' >1987<\/option><option value='1986' >1986<\/option><option value='1985' >1985<\/option><option value='1984' >1984<\/option><option value='1983' >1983<\/option><option value='1982' >1982<\/option><option value='1981' >1981<\/option><option value='1980' >1980<\/option><option value='1979' >1979<\/option><option value='1978' >1978<\/option><option value='1977' >1977<\/option><option value='1976' >1976<\/option><option value='1975' >1975<\/option><option value='1974' >1974<\/option><option value='1973' >1973<\/option><option value='1972' >1972<\/option><option value='1971' >1971<\/option><option value='1970' >1970<\/option><option value='1969' >1969<\/option><option value='1968' >1968<\/option><option value='1967' >1967<\/option><option value='1966' >1966<\/option><option value='1965' >1965<\/option><option value='1964' >1964<\/option><option value='1963' >1963<\/option><option value='1962' >1962<\/option><option value='1961' >1961<\/option><option value='1960' >1960<\/option><option value='1959' >1959<\/option><option value='1958' >1958<\/option><option value='1957' >1957<\/option><option value='1956' >1956<\/option><option value='1955' >1955<\/option><option value='1954' >1954<\/option><option value='1953' >1953<\/option><option value='1952' >1952<\/option><option value='1951' >1951<\/option><option value='1950' >1950<\/option><option value='1949' >1949<\/option><option value='1948' >1948<\/option><option value='1947' >1947<\/option><option value='1946' >1946<\/option><option value='1945' >1945<\/option><option value='1944' >1944<\/option><option value='1943' >1943<\/option><option value='1942' >1942<\/option><option value='1941' >1941<\/option><option value='1940' >1940<\/option><option value='1939' >1939<\/option><option value='1938' >1938<\/option><option value='1937' >1937<\/option><option value='1936' >1936<\/option><option value='1935' >1935<\/option><option value='1934' >1934<\/option><option value='1933' >1933<\/option><option value='1932' >1932<\/option><option value='1931' >1931<\/option><option value='1930' >1930<\/option><option value='1929' >1929<\/option><option value='1928' >1928<\/option><option value='1927' >1927<\/option><option value='1926' >1926<\/option><option value='1925' >1925<\/option><option value='1924' >1924<\/option><option value='1923' >1923<\/option><option value='1922' >1922<\/option><option value='1921' >1921<\/option><option value='1920' >1920<\/option><\/select><\/div><\/div><\/div><\/li><li id=\"field_8_7\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_7'>Studiengang<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_7' id='input_8_7' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_8\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_8'>Jahrgang<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_8' id='input_8_8' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_9\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Kompetenzmodul 1 (KM1): Sprachkompetenzen<\/h2><\/li><li id=\"field_8_31\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_31'>Sprache 1<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_31' id='input_8_31' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_32\" class=\"gfield gfield--type-select gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_32'>Sprache 1 Kompetenzniveau<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_32' id='input_8_32' class='medium gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='Bitte w\u00e4hlen...' selected='selected'>Bitte w\u00e4hlen...<\/option><option value='A1' >A1<\/option><option value='A2' >A2<\/option><option value='B1' >B1<\/option><option value='B2' >B2<\/option><option value='C1' >C1<\/option><option value='C2' >C2<\/option><\/select><\/div><\/li><li id=\"field_8_11\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_11'>Sprachnachweis 1<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_11' id='input_8_11' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_11\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_11'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_11'><\/div> <\/div><\/li><li id=\"field_8_40\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><hr style=\"width:100%; height:1px; background-color:#efefef !important;\" \/><\/li><li id=\"field_8_34\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_34'>Sprache 2<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_34' id='input_8_34' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_35\" class=\"gfield gfield--type-select gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_35'>Sprache 2 Kompetenzniveau<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_35' id='input_8_35' class='medium gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='Bitte w\u00e4hlen...' selected='selected'>Bitte w\u00e4hlen...<\/option><option value='A1' >A1<\/option><option value='A2' >A2<\/option><option value='B1' >B1<\/option><option value='B2' >B2<\/option><option value='C1' >C1<\/option><option value='C2' >C2<\/option><option value='kein zertifiziertes Sprachniveau' >kein zertifiziertes Sprachniveau<\/option><\/select><\/div><\/li><li id=\"field_8_12\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_12'>Sprachnachweis 2<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_12' id='input_8_12' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_12 gfield_description_8_12\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_12'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_12'><\/div> <\/div><div class='gfield_description' id='gfield_description_8_12'>Mehrere Teilnahmebest\u00e4tigungen bitte in einem gemeinsamen Dokument hochladen.<\/div><\/li><li id=\"field_8_14\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Kompetenzmodul 2 (KM2): Studium\/Praktikum\/Forschen im Ausland<\/h2><\/li><li id=\"field_8_42\" class=\"gfield gfield--type-radio gfield--type-choice gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' >Studienbezogener Auslandsaufenthalt (Mindestdauer 2 Monate)<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_radio'><ul class='gfield_radio' id='input_8_42'>\n\t\t\t<li class='gchoice gchoice_8_42_0'>\n\t\t\t\t<input name='input_42' type='radio' value='Auslandssemester'  id='choice_8_42_0'    \/>\n\t\t\t\t<label for='choice_8_42_0' id='label_8_42_0' class='gform-field-label gform-field-label--type-inline'>Auslandssemester<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_42_1'>\n\t\t\t\t<input name='input_42' type='radio' value='Auslandspraktikum'  id='choice_8_42_1'    \/>\n\t\t\t\t<label for='choice_8_42_1' id='label_8_42_1' class='gform-field-label gform-field-label--type-inline'>Auslandspraktikum<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_42_2'>\n\t\t\t\t<input name='input_42' type='radio' value='Auslandssemester und Auslandspraktikum'  id='choice_8_42_2'    \/>\n\t\t\t\t<label for='choice_8_42_2' id='label_8_42_2' class='gform-field-label gform-field-label--type-inline'>Auslandssemester und Auslandspraktikum<\/label>\n\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_8_43\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_43'>Auslandssemester Partnerhochschule<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_43' id='input_8_43' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_44\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_44'>Auslandssemester Gastland<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_44' id='input_8_44' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_45\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_45'>Auslandssemester Zeitraum<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_45' id='input_8_45' type='text' value='' class='medium'  aria-describedby=\"gfield_description_8_45\"   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><div class='gfield_description' id='gfield_description_8_45'>von TT.MM.JJJJ bis TT.MM.JJJJ<\/div><\/li><li id=\"field_8_16\" class=\"gfield gfield--type-fileupload gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_16'>Auslandssemester Aufenthaltsbest\u00e4tigung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_16' id='input_8_16' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_16\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_16'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_16'><\/div> <\/div><\/li><li id=\"field_8_17\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_17'>Auslandssemester Erfahrungsbericht (KM2)<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_17' id='input_8_17' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_17\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_17'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_17'><\/div> <\/div><\/li><li id=\"field_8_46\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><hr style=\"width:100%; height:1px; background-color:#efefef !important;\" \/><\/li><li id=\"field_8_47\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_47'>Auslandspraktikum Unternehmen<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_47' id='input_8_47' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_48\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_48'>Auslandspraktikum Gastland<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_48' id='input_8_48' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_49\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_49'>Auslandspraktikum Zeitraum<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_49' id='input_8_49' type='text' value='' class='medium'  aria-describedby=\"gfield_description_8_49\"   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><div class='gfield_description' id='gfield_description_8_49'>von TT.MM.JJJJ bis TT.MM.JJJJ<\/div><\/li><li id=\"field_8_50\" class=\"gfield gfield--type-fileupload gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_50'>Auslandspraktikum Aufenthaltsbest\u00e4tigung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_50' id='input_8_50' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_50\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_50'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_50'><\/div> <\/div><\/li><li id=\"field_8_51\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_51'>Auslandspraktikum Erfahrungsbericht (KM2)<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_51' id='input_8_51' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_51\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_51'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_51'><\/div> <\/div><\/li><li id=\"field_8_18\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Kompetenzmodul 3 (KM3): Interkulturelle Lehrveranstaltungen<\/h2><\/li><li id=\"field_8_52\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_52'>Lehrveranstaltung 1 Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_52' id='input_8_52' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_53\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_53'>Lehrveranstaltung 1 Bildungseinrichtung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_53' id='input_8_53' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_54\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_54'>Lehrveranstaltung 1 ECTS<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_54' id='input_8_54' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_20\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_20'>Lehrveranstaltung 1 Teilnahmebest\u00e4tigung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_20' id='input_8_20' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_20\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_20'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_20'><\/div> <\/div><\/li><li id=\"field_8_58\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><hr style=\"width:100%; height:1px; background-color:#efefef !important;\" \/><\/li><li id=\"field_8_55\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_55'>Lehrveranstaltung 2 Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_55' id='input_8_55' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_56\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_56'>Lehrveranstaltung 2 Bildungseinrichtung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_56' id='input_8_56' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_57\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_57'>Lehrveranstaltung 2 ECTS<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_57' id='input_8_57' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_21\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_21'>Teilnahmebest\u00e4tigung 2<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_21' id='input_8_21' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_21\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_21'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_21'><\/div> <\/div><\/li><li id=\"field_8_59\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><hr style=\"width:100%; height:1px; background-color:#efefef !important;\" \/><\/li><li id=\"field_8_22\" class=\"gfield gfield--type-fileupload gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_22'>Erfahrungsbericht (KM3)<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_22' id='input_8_22' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_22\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_22'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_22'><\/div> <\/div><\/li><li id=\"field_8_23\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Kompetenzmodul 4 (KM4): Interkulturelles und soziales Engagement<\/h2><\/li><li id=\"field_8_24\" class=\"gfield gfield--type-radio gfield--type-choice gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' >Interkulturelles und soziales Engagement<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_radio'><ul class='gfield_radio' id='input_8_24'>\n\t\t\t<li class='gchoice gchoice_8_24_0'>\n\t\t\t\t<input name='input_24' type='radio' value='Variante 1: Soziales Engagement an der FH JOANNEUM'  id='choice_8_24_0'    \/>\n\t\t\t\t<label for='choice_8_24_0' id='label_8_24_0' class='gform-field-label gform-field-label--type-inline'>Variante 1: Soziales Engagement an der FH JOANNEUM<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_24_1'>\n\t\t\t\t<input name='input_24' type='radio' value='Variante 2: Soziales Engagement au\u00dferhalb der FH JOANNEUM'  id='choice_8_24_1'    \/>\n\t\t\t\t<label for='choice_8_24_1' id='label_8_24_1' class='gform-field-label gform-field-label--type-inline'>Variante 2: Soziales Engagement au\u00dferhalb der FH JOANNEUM<\/label>\n\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_8_60\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_60'>Name der Organisation<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_60' id='input_8_60' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_61\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_61'>T\u00e4tigkeit<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_61' id='input_8_61' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_62\" class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_62'>Zeitraum<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_62' id='input_8_62' type='text' value='' class='medium'  aria-describedby=\"gfield_description_8_62\"   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><div class='gfield_description' id='gfield_description_8_62'>von TT.MM.JJJJ bis TT.MM.JJJJ<\/div><\/li><li id=\"field_8_25\" class=\"gfield gfield--type-fileupload gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_25'>Best\u00e4tigung der Einrichtung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_25' id='input_8_25' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_25\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_25'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_25'><\/div> <\/div><\/li><li id=\"field_8_26\" class=\"gfield gfield--type-fileupload gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_26'>Erfahrungsbericht (KM4)<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_26' id='input_8_26' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_26\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_26'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_26'><\/div> <\/div><\/li><li id=\"field_8_27\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Abschlie\u00dfender Reflexionsbericht \u00fcber alle 4 Module<\/h2><\/li><li id=\"field_8_28\" class=\"gfield gfield--type-fileupload gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_28'>Reflexionsbericht<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><input type='hidden' name='MAX_FILE_SIZE' value='52428800' \/><input name='input_28' id='input_8_28' type='file' class='medium' aria-describedby=\"gfield_upload_rules_8_28\" onchange='javascript:gformValidateFileSize( this, 52428800 );'  \/><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_8_28'>Max. Dateigr\u00f6\u00dfe: 50 MB.<\/span><div class='gfield_description validation_message gfield_validation_message validation_message--hidden-on-empty' id='live_validation_message_8_28'><\/div> <\/div><\/li><li id=\"field_8_29\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Abholung des ISC (Intercultural Skills Certificate)<\/h2><\/li><li id=\"field_8_30\" class=\"gfield gfield--type-radio gfield--type-choice gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' >Ich hole das ISC im International Office an folgendem Standort ab:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_radio'><ul class='gfield_radio' id='input_8_30'>\n\t\t\t<li class='gchoice gchoice_8_30_0'>\n\t\t\t\t<input name='input_30' type='radio' value='Graz'  id='choice_8_30_0'    \/>\n\t\t\t\t<label for='choice_8_30_0' id='label_8_30_0' class='gform-field-label gform-field-label--type-inline'>Graz<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_30_1'>\n\t\t\t\t<input name='input_30' type='radio' value='Kapfenberg'  id='choice_8_30_1'    \/>\n\t\t\t\t<label for='choice_8_30_1' id='label_8_30_1' class='gform-field-label gform-field-label--type-inline'>Kapfenberg<\/label>\n\t\t\t<\/li>\n\t\t\t<li class='gchoice gchoice_8_30_2'>\n\t\t\t\t<input name='input_30' type='radio' value='Bad Gleichenberg'  id='choice_8_30_2'    \/>\n\t\t\t\t<label for='choice_8_30_2' id='label_8_30_2' class='gform-field-label gform-field-label--type-inline'>Bad Gleichenberg<\/label>\n\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_8_63\" class=\"gfield gfield--type-section gsection rotH2 field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">DSGVO<\/h2><\/li><li id=\"field_8_64\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' >DSGVO<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_8_64'><li class='gchoice gchoice_8_64_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_64.1' type='checkbox'  value='Ich best\u00e4tige hiermit, dass ich die Datenschutzerkl\u00e4rung gelesen und vollkommen verstanden habe und der darin beschriebenen Verwendung und Verarbeitung meiner Daten ausdr\u00fccklich zustimme.'  id='choice_8_64_1'   aria-describedby=\"gfield_description_8_64\"\/>\n\t\t\t\t\t\t\t\t<label for='choice_8_64_1' id='label_8_64_1' class='gform-field-label gform-field-label--type-inline'>Ich best\u00e4tige hiermit, dass ich die Datenschutzerkl\u00e4rung gelesen und vollkommen verstanden habe und der darin beschriebenen Verwendung und Verarbeitung meiner Daten ausdr\u00fccklich zustimme.<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><div class='gfield_description' id='gfield_description_8_64'>Bitte entnehmen Sie die Informationen zu den zu Ihrer Person verarbeiteten Daten unserer <a href=\"https:\/\/cdn.fh-joanneum.at\/media\/2020\/02\/DE_Datenschutzerkl%C3%A4rung_ISC.pdf\" target=\"_blank\"><b>Datenschutzerkl\u00e4rung<\/b><\/a>.<\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_8' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Absenden'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_8' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_8' id='gform_theme_8' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_8' id='gform_style_settings_8' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_8' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='8' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='NocHr\/3VT+YYZkT\/reoC0KKOYNDbzR69YxXfki78Mrq2YAGbpLrlkm\/MEUh9TUcr2ncnH6lMjuLVp4C3Hrm4jVVNOjw0XUz623HUGEPxuDNxAE4=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_8' value='WyJbXSIsIjFjNWExOTFiMTU5YjBkMGMwYTQ1NjlkMDQ0MzFkYWMxIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_8' id='gform_target_page_number_8' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_8' id='gform_source_page_number_8' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 8, 'https:\/\/forms.fh-joanneum.at\/int\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_8').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_8');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_8').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){form_content.find('form').css('opacity', 0);jQuery('#gform_wrapper_8').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_8').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_8').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_8').val();gformInitSpinner( 8, 'https:\/\/forms.fh-joanneum.at\/int\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [8, current_page]);window['gf_submitting_8'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_8').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [8]);window['gf_submitting_8'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_8').text());}else{jQuery('#gform_8').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"8\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_8\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_8\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_8\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 8, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>\u00a0ENGLISH VERSION\u00a0 Damit Sie ihr Intercultural Skills Certificate (ISC) bald in H\u00e4nden halten k\u00f6nnen, f\u00fcllen Sie bitte das Formular vollst\u00e4ndig aus. Die Ausstellung des ISC dauert ca. zwei Wochen. Wir verst\u00e4ndigen Sie per E-Mail, wenn Sie das ISC im International Office abholen k\u00f6nnen.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"footnotes":""},"class_list":["post-158","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/pages\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":5,"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/pages\/158\/revisions"}],"predecessor-version":[{"id":483,"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/pages\/158\/revisions\/483"}],"wp:attachment":[{"href":"https:\/\/forms.fh-joanneum.at\/int\/wp-json\/wp\/v2\/media?parent=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}